{"id":10828,"date":"2021-08-09T10:10:25","date_gmt":"2021-08-09T08:10:25","guid":{"rendered":"https:\/\/www.topcontrol.it\/privacy-policy-2\/"},"modified":"2023-02-24T07:53:43","modified_gmt":"2023-02-24T06:53:43","slug":"privacy-policy-2","status":"publish","type":"page","link":"https:\/\/www.topcontrol.it\/es\/privacy-policy-2\/","title":{"rendered":"Privacy Policy"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"10828\" class=\"elementor elementor-10828 elementor-1039\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6b3a431 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"6b3a431\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8efe612\" data-id=\"8efe612\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0f6067d elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"0f6067d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-dbddacb\" data-id=\"dbddacb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-74f70b4 elementor-widget elementor-widget-heading\" data-id=\"74f70b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Privacy Policy<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-217f6fc elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"217f6fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.topcontrol.it\/wp-content\/uploads\/2021\/08\/informationen_zur_datenverarbeitung_-_kandidaten.pdf\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-file-pdf\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Informaci\u00f3n sobre el tratamiento de datos - candidatos<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.topcontrol.it\/wp-content\/uploads\/2021\/08\/informationen_zur_verarbeitung_von_persoenlichen_daten_von_kunden_und_lieferanten.pdf\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-file-pdf\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Informaci\u00f3n sobre el tratamiento de datos: clientes y proveedores<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.topcontrol.it\/wp-content\/uploads\/2022\/11\/Privacy-Policy.pdf\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-file-pdf\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Privacy Policy<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fc8d296 elementor-widget elementor-widget-shortcode\" data-id=\"fc8d296\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">[borlabs-cookie type=\"btn-cookie-preference\" title=\"Cambiar la configuraci\u00f3n de las cookies\" \/]<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c9cc8ec elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"c9cc8ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>*actualizado al Reglamento UE 2016\/679 (GDPR)<\/p>\n<p>En esta p\u00e1gina se describen las modalidades de tratamiento de datos personales que se llevan a cabo a trav\u00e9s de este sitio web, en referencia al tratamiento de los datos personales de los usuarios que lo consultan y\/o interact\u00faan con los servicios web prestados a trav\u00e9s del propio sitio. Tras la consulta de este sitio web o la solicitud de servicios web, pueden tratarse datos relativos a personas identificadas o identificables.<\/p>\n<h3>Controlador de datos<\/h3>\n<p>El titular del tratamiento de datos realizado a trav\u00e9s del sitio web es:<\/p>\n<p>TopControl GmbH<br \/>Enzenbergweg 24 A <br \/>39018 Terlan (BZ), Italien<\/p>\n<h3>Tipos de datos tratados; finalidad y fundamento jur\u00eddico del tratamiento<\/h3>\n<p><strong>Datos proporcionados voluntariamente por el usuario para los servicios solicitados.<\/strong> <br \/>La cumplimentaci\u00f3n de determinados formularios del sitio web por parte del usuario mediante la inserci\u00f3n de datos de car\u00e1cter personal con el fin de obtener servicios\/informaci\u00f3n, realizar peticiones, enviar solicitudes u obtener servicios adicionales en el sitio web, as\u00ed como el env\u00edo opcional, expl\u00edcito y voluntario de correo electr\u00f3nico a direcciones que incluyan los datos facilitados por el usuario en este sitio web y la posterior recogida de estos datos con el fin de prestar los servicios solicitados.<\/p>\n<p>Algunos de los datos solicitados en los formatos son necesarios para la prestaci\u00f3n del servicio solicitado y est\u00e1n marcados con un asterisco. Otros datos son puramente opcionales y pueden ser introducidos por el usuario con el fin de proporcionar un servicio m\u00e1s completo y personalizado, o con el consentimiento previo en los casos previstos en la legislaci\u00f3n vigente, con el fin de analizar los intereses y la informaci\u00f3n personal o los h\u00e1bitos o elecciones de consumo. Si no se facilitan los datos obligatorios, no es posible la continuaci\u00f3n y, por tanto, la prestaci\u00f3n del servicio solicitado.a La no especificaci\u00f3n de los datos opcionales puede dar lugar a un servicio incompleto y a la imposibilidad de realizar las actividades opcionales especificadas.<\/p>\n<p>En particular:<br \/><strong>Secci\u00f3n \u00abNewsletter\u00bb: Los datos introducidos se registran para enviar boletines informativos sobre TopControl y sus productos.<\/strong><\/p>\n<p>Por lo tanto, las finalidades del tratamiento de estos datos dependen de los servicios solicitados:<br \/>&#8211; Comunicaci\u00f3n con el cliente sobre el servicio solicitado. La base legal para el tratamiento es, por tanto, el cumplimiento de las obligaciones contractuales (consultas) del usuario consultante y el consentimiento del interesado a los servicios opcionales.<\/p>\n<p><strong>Datos de terceros introducidos libremente por el usuario<\/strong><br \/>Cuando el usuario env\u00eda datos personales y\/o datos de contacto de un tercero distinto del mismo interesado en las solicitudes de informaci\u00f3n, reconoce que esta operaci\u00f3n supone un tratamiento de datos personales del que es titular independiente, asumiendo todas las obligaciones y responsabilidades previstas en relaci\u00f3n con el tratamiento de datos personales. En este sentido, el usuario garantiza al responsable del tratamiento que todos los datos de terceros facilitados por el usuario y tratados como si el tercero hubiera dado su consentimiento informado al tratamiento han sido recogidos por el usuario con pleno respeto a la normativa y a las reglas vigentes en materia de tratamiento de datos. El usuario indemnizar\u00e1 al responsable del tratamiento por todos los litigios, reclamaciones y da\u00f1os y perjuicios que pueda recibir de terceros como consecuencia del suministro de datos facilitados por el usuario en contra de la legislaci\u00f3n sobre protecci\u00f3n de datos personales.<\/p>\n<p><strong>Datos de navegaci\u00f3n<\/strong><br \/>Los sistemas inform\u00e1ticos y los procedimientos de software utilizados para el funcionamiento de este sitio web recogen, durante su curso normal, algunos datos personales, cuya transmisi\u00f3n est\u00e1 asociada al uso de los protocolos de comunicaci\u00f3n de Internet. Se trata de informaci\u00f3n que no se recoge para ser asociada a interesados identificados, pero que podr\u00eda permitir la identificaci\u00f3n de los usuarios debido al tratamiento con datos en poder de terceros. Esta categor\u00eda de datos incluye las direcciones IP o los nombres de dominio de los ordenadores utilizados por los usuarios para conectarse al sitio, las direcciones en notaci\u00f3n URI (Uniform Resource Identifier) de los recursos solicitados, la hora de la solicitud y el m\u00e9todo utilizado para enviar la solicitud al servidor, el tama\u00f1o del archivo recibido como respuesta, el c\u00f3digo num\u00e9rico que indica el estado de la respuesta dada por el servidor (\u00e9xito, error, etc.) y otros par\u00e1metros relacionados con el sistema operativo y el entorno inform\u00e1tico del usuario.<\/p>\n<p>Estos datos se utilizan para obtener informaci\u00f3n estad\u00edstica an\u00f3nima sobre el uso del sitio web y para comprobar el correcto funcionamiento del mismo. Los datos podr\u00edan utilizarse para identificar a los responsables en caso de un hipot\u00e9tico delito inform\u00e1tico contra el sitio web.<\/p>\n<p>Por lo tanto, el tratamiento de estos datos tiene las siguientes finalidades:<br \/>Permitir el funcionamiento del sitio web y la ejecuci\u00f3n de los servicios solicitados por el usuario;<br \/>Revisar y mejorar el funcionamiento del sitio web;<br \/>Obtener y utilizar informaci\u00f3n estad\u00edstica sobre el uso del sitio web;<br \/>Determinaci\u00f3n de la responsabilidad en casos hipot\u00e9ticos de delitos inform\u00e1ticos;<br \/>La base legal para el tratamiento de estos datos es, por lo tanto, el inter\u00e9s leg\u00edtimo del propietario en el desarrollo y la mejora de los servicios del sitio proporcionados.<\/p>\n<p><strong>Cookies y rastreo<\/strong><br \/>Una cookie y tecnolog\u00edas similares son peque\u00f1os fragmentos de informaci\u00f3n que se utilizan para almacenar datos t\u00e9cnicos y\/o personales en el ordenador con el fin de identificar a los usuarios de un servicio y activar determinadas funciones. Estas cookies son utilizadas por el responsable del tratamiento y sus socios con fines t\u00e9cnicos, estad\u00edsticos y\/o de elaboraci\u00f3n de perfiles. La informaci\u00f3n sobre las cookies utilizadas por los servicios y su rechazo se encuentra en la \u00ab<a href=\"https:\/\/www.topcontrol.it\/es\/politica-de-cookies\/\" target=\"_blank\" rel=\"noopener\">Pol\u00edtica de Cookies<\/a>\u00ab.<\/p>\n<h3>Comunicaci\u00f3n de datos a terceros<\/h3>\n<p><strong>Datos proporcionados voluntariamente por el usuario<\/strong><br \/>Los datos personales facilitados por el usuario (tales como nombre, apellidos, correo electr\u00f3nico, tel\u00e9fono, informaci\u00f3n incluida, datos para las compras a trav\u00e9s del comercio electr\u00f3nico, datos contables) ser\u00e1n utilizados por los sujetos internos (empleados y colaboradores) de los mencionados responsables del tratamiento seg\u00fan sus capacidades y en el marco de sus funciones y\/o obligaciones contractuales. Algunos datos podr\u00e1n ser comunicados, para las finalidades indicadas, a: sujetos\/empresas externas a las que la comunicaci\u00f3n de los datos personales sea necesaria o, en todo caso, requerida para la realizaci\u00f3n del servicio solicitado o la gesti\u00f3n de la relaci\u00f3n contractual con el interesado en la forma y para las finalidades ilustradas anteriormente.<\/p>\n<p><strong>Datos de navegaci\u00f3n<\/strong><br \/>Los datos de navegaci\u00f3n pueden ser transmitidos a terceros.<\/p>\n<p><strong>Calificaci\u00f3n de terceros<\/strong><br \/>Los terceros que realizan actividades de apoyo de cualquier tipo para la prestaci\u00f3n de servicios al responsable del tratamiento y para los que tratan datos personales son designados por el responsable del tratamiento como encargados del tratamiento y est\u00e1n obligados contractualmente a cumplir y respetar las medidas relativas a la seguridad y confidencialidad del tratamiento.<br \/>La identidad de los terceros a los que se comunican los datos para los fines indicados en este contrato se comunicar\u00e1 a los usuarios que lo soliciten a los contactos indicados. En cualquier caso, el propietario es responsable:<\/p>\n<p><strong>A.<\/strong> Las normas y m\u00e9todos de gesti\u00f3n de los datos personales de otros sitios web a los que se puede acceder desde nuestras p\u00e1ginas mediante enlaces y referencias.<br \/><strong>B.<\/strong> El contenido de los servicios de correo electr\u00f3nico, espacios web y foros de chat puestos a disposici\u00f3n de los usuarios.<\/p>\n<p><strong>Difusi\u00f3n de datos<\/strong><br \/>No se difunden datos que provengan de los servicios web, lo que significa que, de alguna manera, proporcionan conocimientos para una variedad de temas no especificados.<\/p>\n<h3>Transferencia a terceros pa\u00edses<\/h3>\n<p>Los datos personales proporcionados por el usuario y los dem\u00e1s tipos de datos tratados, as\u00ed como los datos de navegaci\u00f3n, podr\u00e1n ser tratados o transferidos a pa\u00edses no pertenecientes a la UE para los fines mencionados, de conformidad con la legislaci\u00f3n aplicable en materia de transferencia de datos a pa\u00edses no pertenecientes a la UE, de conformidad con el art\u00edculo 44 y el posterior Reglamento UE 2016\/670 (GDPR). <\/p>\n<h3>M\u00e9todo de tratamiento<\/h3>\n<p>El tratamiento de los datos personales se realiza con herramientas inform\u00e1ticas y respetando las medidas de confidencialidad y protecci\u00f3n de la legislaci\u00f3n vigente. Se observan medidas de seguridad espec\u00edficas para evitar la p\u00e9rdida de datos, el uso ilegal o incorrecto y el acceso no autorizado. Los tratamientos relacionados con los servicios web ofrecidos en este sitio web tienen lugar en las oficinas de los responsables del tratamiento y, eventualmente, en las oficinas de los procesadores de datos externos que tratan los datos o prestan servicios al responsable del tratamiento, y son llevados a cabo por los procesadores de datos encargados de gestionar los servicios solicitados y las finalidades indicadas.<\/p>\n<h3>Per\u00edodo de conservaci\u00f3n de los datos<\/h3>\n<p><strong>Datos proporcionados por el usuario<\/strong>: Los datos personales facilitados por el usuario se conservar\u00e1n durante el periodo necesario para cumplir los fines indicados y, en su caso, para cumplir con las obligaciones contractuales, fiscales y legales. Los curr\u00edculos se archivar\u00e1n durante un periodo m\u00e1ximo de 24 meses, salvo que el interesado d\u00e9 su consentimiento para su mantenimiento.<br \/><strong>Datos de navegaci\u00f3n<\/strong>: Los datos de navegaci\u00f3n se conservan durante el per\u00edodo necesario para llevar a cabo los fines indicados y durante un m\u00e1ximo de 30 d\u00edas despu\u00e9s del reconocimiento.<\/p>\n<h3>Procesos automatizados <\/h3>\n<p>A trav\u00e9s del sitio web no se lleva a cabo ning\u00fan proceso de toma de decisiones automatizada, incluida la elaboraci\u00f3n de perfiles, para los datos personales proporcionados voluntariamente por el usuario al solicitar los servicios del sitio web. Sobre los datos de navegaci\u00f3n\/geolocalizaci\u00f3n se pueden realizar procesos automatizados de toma de decisiones (por ejemplo, cookies) para la funcionalidad del sitio web y\/o procesos automatizados destinados a analizar los h\u00e1bitos, elecciones y m\u00e9todos de b\u00fasqueda del usuario a trav\u00e9s de cookies o servicios de terceros. Con el consentimiento previo del interesado de acuerdo con la Pol\u00edtica de Cookies.<\/p>\n<h3>Suministro de datos y consecuencias de su incumplimiento <\/h3>\n<p>Aparte de la informaci\u00f3n para los datos de navegaci\u00f3n, el usuario es libre de proporcionar datos personales, que se incluyen en los formularios de solicitud de los servicios del sitio. Sin embargo, si no se facilitan los datos obligatorios marcados con un asterisco, no es posible la continuaci\u00f3n y, por tanto, la prestaci\u00f3n del servicio. El hecho de no proporcionar los datos indicados como opcionales puede dar lugar a la prestaci\u00f3n de un servicio incompleto y a la imposibilidad de realizar otras actividades del titular.<\/p>\n<h3>Derechos de los interesados a reclamar y retirar el consentimiento<\/h3>\n<p>Los sujetos a los que se refieren los datos personales tienen derecho, en cualquier momento, a acceder, rectificar, borrar, restringir sus datos personales, oponerse al tratamiento y ejercer el derecho a la portabilidad de los datos, con sujeci\u00f3n a lo dispuesto en la ley. Der Interessent hat das Recht, eine Einwilligung zur Datenverarbeitung jederzeit zu widerrufen, unbeschadet der Rechtm\u00e4\u00dfigkeit der Verarbeitung aufgrund der vor dem Widerruf erteilten Einwilligung.<br \/>Debe tenerse en cuenta que, una vez eliminados, sus datos personales no podr\u00e1n recuperarse y el contenido almacenado en los servicios tambi\u00e9n se eliminar\u00e1 de forma permanente. Sus datos personales tambi\u00e9n se eliminar\u00e1n si ya no son necesarios para los fines para los que se recogieron originalmente.<br \/>Para ejercer los derechos previstos en la legislaci\u00f3n aplicable en materia de protecci\u00f3n de datos personales y conocer la lista completa de los encargados del tratamiento externos designados para cada \u00e1rea y actividad, o para obtener informaci\u00f3n sobre la transferencia de datos a pa\u00edses no pertenecientes a la UE y las correspondientes garant\u00edas, puede enviar un correo electr\u00f3nico a <a href=\"mailto:administration@topcontrol.it\">administration@topcontrol.it<\/a> o env\u00ede un fax al n\u00famero +39 0471 319 990.<\/p>\n<p>El interesado tambi\u00e9n tendr\u00e1 derecho a presentar una reclamaci\u00f3n ante una autoridad de control del tratamiento de datos, en particular en el Estado miembro en el que reside habitualmente o en el Estado miembro en el que trabaja o en el que se ha producido la presunta infracci\u00f3n.<\/p>\n<h3>Menores, veracidad de los datos insertados y obligaciones del usuario <\/h3>\n<p>La protecci\u00f3n de la intimidad de los m\u00e1s j\u00f3venes es especialmente importante para nuestra sociedad. Este sitio web no est\u00e1 dirigido a ni\u00f1os y menores, aunque normalmente es apto para menores. Por \u00faltimo, la empresa anima a los padres y tutores a ayudar a los menores a navegar. Al registrarse en cualquiera de los Servicios y aceptar esta Pol\u00edtica de Privacidad, usted confirma que es mayor de edad en su pa\u00eds para firmar un contrato o solicitar los Servicios prestados. Adem\u00e1s, confirma que ha obtenido el consentimiento previo de los padres\/tutores, que puede ser necesario en el pa\u00eds de residencia. En todo caso, CI se reserva el derecho de contactar con el usuario y verificar la posesi\u00f3n de estos requisitos, y en caso de carecer de los anteriores derechos, bloquear o eliminar la cuenta si el usuario no los posee y\/o interrumpir o suspender los servicios ofrecidos. El usuario garantiza la calidad de la informaci\u00f3n proporcionada para los servicios. Todos los datos personales introducidos o enviados deben ser verdaderos, correctos y actualizados. El usuario asume toda la responsabilidad de garantizar que la informaci\u00f3n proporcionada cumple con este principio. Adem\u00e1s, garantiza que ha obtenido el consentimiento expreso de todas las personas que poseen una imagen personal, propiedad intelectual u otros derechos sobre el contenido en cuesti\u00f3n y que est\u00e1 autorizado a cargarlo y almacenarlo en los Servicios.<\/p>\n<h3>Cambios en esta pol\u00edtica de privacidad <\/h3>\n<p>Esta pol\u00edtica de privacidad se actualiza peri\u00f3dicamente, si se producen cambios en el tratamiento o en los servicios prestados o en el cumplimiento de los requisitos legales, los usuarios ser\u00e1n informados inmediatamente de dichos cambios en el tratamiento de sus datos. Por lo tanto, consulte con frecuencia esta p\u00e1gina con referencia a la fecha de la \u00faltima modificaci\u00f3n indicada a continuaci\u00f3n. Si no se aceptan los cambios introducidos en esta pol\u00edtica de privacidad, el usuario deber\u00e1 dejar de utilizar esta aplicaci\u00f3n y solicitar al responsable del tratamiento la eliminaci\u00f3n de sus datos personales. Salvo que se indique lo contrario, la pol\u00edtica de privacidad anterior seguir\u00e1 aplic\u00e1ndose a los datos personales recogidos hasta ese momento.<\/p>\n<p>\u00daltima actualizaci\u00f3n: 13.08.2020<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0d636e5 elementor-section-full_width elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"0d636e5\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-eef6b38\" data-id=\"eef6b38\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a9a3483 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"a9a3483\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-3d4780f\" data-id=\"3d4780f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1743cb0 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"1743cb0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 90.28 36.27\"><g id=\"Ebene_2\" data-name=\"Ebene 2\"><g id=\"Ebene_1-2\" data-name=\"Ebene 1\"><path d=\"M61.1,0H0A13.8278,13.8278,0,0,0,1.59,5.02c1.77,3.23,4.77,5.35,8.18,5.35h61.1C70.16,4.51,66.05,0,61.1,0Z\" style=\"fill:#fff\"><\/path><path d=\"M80.51,13.11H19.41A13.8278,13.8278,0,0,0,21,18.13c1.77,3.23,4.77,5.35,8.18,5.35h61.1C89.57,17.61,85.47,13.11,80.51,13.11Z\" style=\"fill:#fff\"><\/path><path d=\"M71.6,25.9H10.5a13.8278,13.8278,0,0,0,1.59,5.02c1.77,3.23,4.77,5.35,8.18,5.35h61.1C80.66,30.4,76.56,25.9,71.6,25.9Z\" style=\"fill:#fff\"><\/path><\/g><\/g><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-cb934bc\" data-id=\"cb934bc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b6ed7cd elementor-widget elementor-widget-heading\" data-id=\"b6ed7cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">You need further information?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7107401 elementor-widget elementor-widget-text-editor\" data-id=\"7107401\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Feel free to contact us!<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-03a0258\" data-id=\"03a0258\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b78a5b8 elementor-widget__width-inherit elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"b78a5b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Callback-Service<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-a45a1c2\" data-id=\"a45a1c2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3cb0285 elementor-widget__width-inherit elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"3cb0285\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">E-Mail<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Privacy Policy Informaci\u00f3n sobre el tratamiento de datos &#8211; candidatos Informaci\u00f3n sobre el tratamiento de datos: clientes y proveedores Privacy Policy [borlabs-cookie type=\u00bbbtn-cookie-preference\u00bb title=\u00bbCambiar la configuraci\u00f3n de las cookies\u00bb \/] *actualizado al Reglamento UE 2016\/679 (GDPR) En esta p\u00e1gina se describen las modalidades de tratamiento de datos personales que se llevan a cabo a trav\u00e9s [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-10828","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.topcontrol.it\/es\/wp-json\/wp\/v2\/pages\/10828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.topcontrol.it\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.topcontrol.it\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.topcontrol.it\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.topcontrol.it\/es\/wp-json\/wp\/v2\/comments?post=10828"}],"version-history":[{"count":2,"href":"https:\/\/www.topcontrol.it\/es\/wp-json\/wp\/v2\/pages\/10828\/revisions"}],"predecessor-version":[{"id":12397,"href":"https:\/\/www.topcontrol.it\/es\/wp-json\/wp\/v2\/pages\/10828\/revisions\/12397"}],"wp:attachment":[{"href":"https:\/\/www.topcontrol.it\/es\/wp-json\/wp\/v2\/media?parent=10828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}